{"id":208855,"date":"2026-08-20T21:07:12","date_gmt":"2026-08-21T00:07:12","guid":{"rendered":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/"},"modified":"2026-08-20T21:07:13","modified_gmt":"2026-08-21T00:07:13","slug":"para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech","status":"publish","type":"post","link":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/","title":{"rendered":"Para los bancos, un tercio de la mora se la \u201ccontagiaron\u201d las fintech"},"content":{"rendered":"<p><\/p>\n<div>\n<p class=\"com-paragraph --capital --s\">Los bancos, especialmente aquellos que cotizan en Bolsa, comenzaron a mostrarles a sus inversores que <strong>cerca de un tercio de la mora que deben reportar deriva directamente de las normas regulatorias locales<\/strong>, que los obligan a replicar la peor calificaci\u00f3n crediticia que tenga su cliente en el sistema, aun cuando con ellos se encuentre al d\u00eda.<\/p>\n<p class=\"com-paragraph --s\">La alusi\u00f3n, b\u00e1sicamente, es a la Comunicaci\u00f3n \u201cA\u201d 7443, vigente desde hace a\u00f1os, que provoca lo que los analistas definen como un <strong>\u201cefecto arrastre\u201d sobre todo el sistema<\/strong> y complica la nueva oferta de cr\u00e9dito, ya que obliga a las entidades a previsionar (inmovilizar fondos) por pr\u00e9stamos que, en muchos casos, no son morosos.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" tabindex=\"0\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">Los bancos hacen notar en sus presentaciones a los inversores el impacto en sus carteras de la mora 2&#8243;mportada\u00bb<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph --s\">Se trata de una norma que varias entidades reclamaron al Banco Central (BCRA) revisar, sin lograr receptividad por el momento, y que establece que, \u201csi un deudor registra atrasos que representan el 40% o m\u00e1s de su pasivo total, el resto de las entidades debe degradar su calificaci\u00f3n interna\u201d, explic\u00f3 el analista y consultor Pablo Curat. <a href=\"\" target=\"_blank\" title=\"\" class=\"com-link break-word\" data-mrf-recirculation=\"n_link_parrafo\" rel=\"nofollow\">De all\u00ed surge el \u201ccontagio\u201d, aun en caso de que la irregularidad se produzca solo con otra entidad, algo muy com\u00fan con las <em>fintech<\/em><\/a>, interpretan, como ya hab\u00eda se\u00f1alado LA NACION oportunamente.<\/p>\n<p class=\"com-paragraph --s\">La otra norma apuntada es la que recientemente el titular del BCRA, Santiago Bausili, describi\u00f3 como la que genera una <strong>\u201cdigesti\u00f3n lenta\u201d de la mora<\/strong>. Se trata de los criterios aplicados para las \u201cp\u00e9rdidas incurridas\u201d y las \u201cp\u00e9rdidas esperadas\u201d, seg\u00fan se trate de entidades peque\u00f1as o grandes, que les impiden a los bancos normalizar una calificaci\u00f3n de manera inmediata.<\/p>\n<p class=\"com-paragraph --s\">El funcionario, al presentar el \u00faltimo Informe de Pol\u00edtica Monetaria (IPOM), explic\u00f3 que la mejora de las calificaciones castigadas por incurrir en mora es gradual y solo se activa a medida que los deudores refinancian y regularizan consistentemente los pagos. Esto hace que <strong>pasar de la categor\u00eda de deudor 5 \u2014el mayor nivel de mora\u2014 a la categor\u00eda 1 \u2014cumplimiento de pagos\u2014 lleve, en el mejor de los casos, \u201cnueve meses\u201d, reconoci\u00f3.<\/strong><\/p>\n<p class=\"com-paragraph --s\">La menci\u00f3n a la <strong>\u201cmora importada\u201d<\/strong> apareci\u00f3, por caso, en el balance de Banco Macro con resultados al segundo trimestre. La entidad hizo notar que, si en ese per\u00edodo la mora sigui\u00f3 subiendo marcadamente, fue por las <mark class=\"hl_underline\">recategorizaciones obligatorias establecidas por la normativa del BCRA. <\/mark>As\u00ed, un aumento de la irregularidad de solo 27 puntos b\u00e1sicos en ese lapso \u2014de 3,81% de la cartera a 4,08%\u2014 se transform\u00f3, por efecto de esas recategorizaciones, en uno de 85 puntos b\u00e1sicos, de 5,40% a 6,25%. En el acumulado del a\u00f1o, esto lleva el castigo a 2,38 puntos porcentuales cuando, de otra manera, habr\u00eda sido de solo 1,15 puntos.<\/p>\n<p class=\"com-paragraph --s\">Los datos muestran que<strong> la morosidad es m\u00e1s extendida entre los clientes de billeteras y <\/strong><em><strong>fintech<\/strong><\/em><strong>,<\/strong> un segmento en el que la situaci\u00f3n se complica m\u00e1s por el nivel de las tasas de inter\u00e9s que se aplican a las peque\u00f1as financiaciones, que en muchos casos superan el 1000% anual cuando se considera el Costo Financiero Total (CFT), que es, ni m\u00e1s ni menos, el indicador m\u00e1s fiel de lo que se paga por un pr\u00e9stamo.<\/p>\n<p class=\"com-paragraph --s\"><mark class=\"hl_underline\">\u201cEn las <\/mark><mark class=\"hl_underline\"><em>fintech <\/em><\/mark><mark class=\"hl_underline\">hay 2 millones de personas en situaci\u00f3n irregular que deben un total de $1 mill\u00f3n; o sea, el doble de un sueldo m\u00ednimo o la mitad de un sueldo promedio\u201d, <\/mark>record\u00f3 al respecto hace unos d\u00edas el analista y consultor Fernando Marull.<\/p>\n<p class=\"com-paragraph --s\">\u201cLa mora no es un problema macro, como algunos quieren hacer creer, ni sist\u00e9mico:<strong> el grueso entre personas est\u00e1 en peque\u00f1os pr\u00e9stamos, <\/strong>pero que se hacen dif\u00edciles de pagar\u201d, coincide Leonardo Chialva, de Delphos Investment.<\/p>\n<p class=\"com-paragraph --s\">El punto es que muchos de los que hab\u00edan agotado sus posibilidades de acceso al cr\u00e9dito bancario \u2014o nunca lo tuvieron por su situaci\u00f3n laboral precaria\u2014 recurrieron a las <strong>alternativas m\u00e1s sencillas<\/strong> para poder refinanciar otras deudas o cubrir gastos corrientes, en tiempos en que los ingresos no mejoraron.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" tabindex=\"0\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">Las fintech fijaron posici\u00f3n<\/span><span class=\"com-text --credit --twoxs\">Compumar<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph --s\">Las crecientes menciones al sector llevaron hoy a la C\u00e1mara Argentina Fintech a publicar un comunicado, denominado <strong>\u201cArgentina necesita m\u00e1s y mejor cr\u00e9dito\u201d<\/strong>, para presentar su posici\u00f3n sobre la situaci\u00f3n del cr\u00e9dito a las familias y las alternativas necesarias para abordar el crecimiento de la mora.<\/p>\n<p class=\"com-paragraph --s\">All\u00ed explican que hoy son m\u00e1s de <strong>10 millones de argentinos los que acceden a financiamiento a trav\u00e9s de una <\/strong><em><strong>fintech<\/strong><\/em>, \u201cde los cuales 3,8 millones no tienen un cr\u00e9dito bancario\u201d, y que el <em>stock <\/em>total de cr\u00e9dito a las familias asciende a $82,8 billones. De ese total, \u201cel 81,1% est\u00e1 concentrado en bancos, el 11,7% en <em>fintech <\/em>y el 7,1% en otros proveedores no bancarios\u201d.<\/p>\n<p class=\"com-paragraph --s\">\u201cDe ese total, $13,5 billones \u2014el 16,3%\u2014 se encuentran en situaci\u00f3n irregular: el 63,3% est\u00e1 contabilizado en bancos, el 20,4% en otros proveedores y el 16,3% en fintech\u201d, se\u00f1alan en base a los montos involucrados, antes de reclamar<strong> \u201csoluciones compartidas\u201d para encarar el problema<\/strong>. Entre ellas, consideran necesario \u201cavanzar en mejorar la informaci\u00f3n crediticia disponible, reducir la carga impositiva, promover m\u00e1s educaci\u00f3n financiera y alternativas tempranas para quienes atraviesan dificultades\u201d.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" tabindex=\"0\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">Qui\u00e9n es qui\u00e9n en el sistema<\/span><span class=\"com-text --credit --twoxs\">Compumar<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph --s\">El informe, elaborado por la consultora Analytica en base a datos del BCRA, se\u00f1ala que hay <strong>20,8 millones de individuos con al menos un cr\u00e9dito formal en el pa\u00eds<\/strong>, de los cuales 5,8 millones registran atrasos superiores a 90 d\u00edas en el pago de sus cuotas.<\/p>\n<p class=\"com-paragraph --s\">Y detalla que, separados seg\u00fan el tipo de proveedor:<\/p>\n<p class=\"com-paragraph --s\">Apuntan que la irregularidad es m\u00e1s extendida en el sector porque, mientras los bancos est\u00e1n habilitados por el BCRA a prestar dinero proveniente de los dep\u00f3sitos de sus clientes,<strong> \u201clas <\/strong><em><strong>fintech <\/strong><\/em><strong>y los proveedores no financieros solo pueden utilizar capital que toman del mercado de capitales o, incluso, de pr\u00e9stamos bancarios, un mecanismo siempre m\u00e1s costoso\u201d.<\/strong> Esto les fija un piso m\u00e1s alto en su costo de fondeo y los lleva a prestar m\u00e1s caro.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" tabindex=\"0\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">Una de las causas de la asfixia financiera<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph --s\">La disputa entre los distintos jugadores del sistema financiero sobre el problema de la mora est\u00e1 planteada. Mientras dejan constancia de que esperan alguna reacci\u00f3n de las autoridades sobre el tema, tambi\u00e9n dejan expuesto el <strong>\u00fanico punto de coincidencia: el reclamo por las cargas impositivas que siguen castigando la oferta crediticia.<\/strong><\/p>\n<section class=\"container-center-100 mb-40 border border-bottom border-thin border-neutral-light-700\">\n<hr\/>\n<\/section>\n<\/div>\n<p><script id=\"facebookpixel\" defer=\"\" type=\"text\/javascript\">\n        !function(f,b,e,v,n,t,s)\n        {if(f.fbq)return;n=f.fbq=function(){n.callMethod?\n        n.callMethod.apply(n,arguments):n.queue.push(arguments)};\n        if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';\n        n.queue=[];t=b.createElement(e);t.async=!0;\n        t.src=v;s=b.getElementsByTagName(e)[0];\n        s.parentNode.insertBefore(t,s)}(window, document,'script',\n        'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n        fbq('init', '492459597522335');\n        fbq('track', 'PageView');\n    <\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los bancos, especialmente aquellos que cotizan en Bolsa, comenzaron a mostrarles a sus inversores que cerca de un tercio de la mora que deben reportar deriva directamente de las normas regulatorias locales, que los obligan a replicar la peor calificaci\u00f3n crediticia que tenga su cliente en el sistema, aun cuando con ellos se encuentre al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":208856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-208855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Para los bancos, un tercio de la mora se la \u201ccontagiaron\u201d las fintech - GYS NOTICIAS |<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Para los bancos, un tercio de la mora se la \u201ccontagiaron\u201d las fintech - GYS NOTICIAS |\" \/>\n<meta property=\"og:description\" content=\"Los bancos, especialmente aquellos que cotizan en Bolsa, comenzaron a mostrarles a sus inversores que cerca de un tercio de la mora que deben reportar deriva directamente de las normas regulatorias locales, que los obligan a replicar la peor calificaci\u00f3n crediticia que tenga su cliente en el sistema, aun cuando con ellos se encuentre al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/\" \/>\n<meta property=\"og:site_name\" content=\"GYS NOTICIAS |\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-21T00:07:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-21T00:07:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/08\/los-datos-muestran-que-la-morosidad-es-mas-D2S3SXTOCFAELAVHXMRGXKYOWI.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/person\/5bedd7ecd35cc35548d89effafa23696\"},\"headline\":\"Para los bancos, un tercio de la mora se la \u201ccontagiaron\u201d las fintech\",\"datePublished\":\"2026-08-21T00:07:12+00:00\",\"dateModified\":\"2026-08-21T00:07:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/\"},\"wordCount\":1105,\"publisher\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#organization\"},\"image\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/08\/los-datos-muestran-que-la-morosidad-es-mas-D2S3SXTOCFAELAVHXMRGXKYOWI.jpg\",\"articleSection\":[\"ECONOMIA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/\",\"url\":\"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/\",\"name\":\"Para los bancos, un tercio de la mora se la \u201ccontagiaron\u201d las fintech - GYS NOTICIAS |\",\"isPartOf\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/08\/los-datos-muestran-que-la-morosidad-es-mas-D2S3SXTOCFAELAVHXMRGXKYOWI.jpg\",\"datePublished\":\"2026-08-21T00:07:12+00:00\",\"dateModified\":\"2026-08-21T00:07:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/#primaryimage\",\"url\":\"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/08\/los-datos-muestran-que-la-morosidad-es-mas-D2S3SXTOCFAELAVHXMRGXKYOWI.jpg\",\"contentUrl\":\"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/08\/los-datos-muestran-que-la-morosidad-es-mas-D2S3SXTOCFAELAVHXMRGXKYOWI.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/gysfm.com.ar\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Para los bancos, un tercio de la mora se la \u201ccontagiaron\u201d las fintech\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#website\",\"url\":\"https:\/\/gysfm.com.ar\/inicio\/\",\"name\":\"GYS NOTICIAS |\",\"description\":\"DIARIO - RADIO ONLINE SAN JUAN ARGENTINA\",\"publisher\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gysfm.com.ar\/inicio\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#organization\",\"name\":\"GYS NOTICIAS |\",\"url\":\"https:\/\/gysfm.com.ar\/inicio\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2023\/07\/LOGOGYS-OK.png\",\"contentUrl\":\"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2023\/07\/LOGOGYS-OK.png\",\"width\":1170,\"height\":872,\"caption\":\"GYS NOTICIAS |\"},\"image\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/person\/5bedd7ecd35cc35548d89effafa23696\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c331d312b5243fb64d5ba28108a447b27c925295129a363082c9ea52c28d32c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c331d312b5243fb64d5ba28108a447b27c925295129a363082c9ea52c28d32c2?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/gysfm.com.ar\/inicio\"],\"url\":\"https:\/\/gysfm.com.ar\/inicio\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Para los bancos, un tercio de la mora se la \u201ccontagiaron\u201d las fintech - GYS NOTICIAS |","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/","og_locale":"es_ES","og_type":"article","og_title":"Para los bancos, un tercio de la mora se la \u201ccontagiaron\u201d las fintech - GYS NOTICIAS |","og_description":"Los bancos, especialmente aquellos que cotizan en Bolsa, comenzaron a mostrarles a sus inversores que cerca de un tercio de la mora que deben reportar deriva directamente de las normas regulatorias locales, que los obligan a replicar la peor calificaci\u00f3n crediticia que tenga su cliente en el sistema, aun cuando con ellos se encuentre al [&hellip;]","og_url":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/","og_site_name":"GYS NOTICIAS |","article_published_time":"2026-08-21T00:07:12+00:00","article_modified_time":"2026-08-21T00:07:13+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/08\/los-datos-muestran-que-la-morosidad-es-mas-D2S3SXTOCFAELAVHXMRGXKYOWI.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/#article","isPartOf":{"@id":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/"},"author":{"name":"admin","@id":"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/person\/5bedd7ecd35cc35548d89effafa23696"},"headline":"Para los bancos, un tercio de la mora se la \u201ccontagiaron\u201d las fintech","datePublished":"2026-08-21T00:07:12+00:00","dateModified":"2026-08-21T00:07:13+00:00","mainEntityOfPage":{"@id":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/"},"wordCount":1105,"publisher":{"@id":"https:\/\/gysfm.com.ar\/inicio\/#organization"},"image":{"@id":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/#primaryimage"},"thumbnailUrl":"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/08\/los-datos-muestran-que-la-morosidad-es-mas-D2S3SXTOCFAELAVHXMRGXKYOWI.jpg","articleSection":["ECONOMIA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/","url":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/","name":"Para los bancos, un tercio de la mora se la \u201ccontagiaron\u201d las fintech - GYS NOTICIAS |","isPartOf":{"@id":"https:\/\/gysfm.com.ar\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/#primaryimage"},"image":{"@id":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/#primaryimage"},"thumbnailUrl":"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/08\/los-datos-muestran-que-la-morosidad-es-mas-D2S3SXTOCFAELAVHXMRGXKYOWI.jpg","datePublished":"2026-08-21T00:07:12+00:00","dateModified":"2026-08-21T00:07:13+00:00","breadcrumb":{"@id":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/#primaryimage","url":"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/08\/los-datos-muestran-que-la-morosidad-es-mas-D2S3SXTOCFAELAVHXMRGXKYOWI.jpg","contentUrl":"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/08\/los-datos-muestran-que-la-morosidad-es-mas-D2S3SXTOCFAELAVHXMRGXKYOWI.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/gysfm.com.ar\/inicio\/para-los-bancos-un-tercio-de-la-mora-se-la-contagiaron-las-fintech\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gysfm.com.ar\/inicio\/"},{"@type":"ListItem","position":2,"name":"Para los bancos, un tercio de la mora se la \u201ccontagiaron\u201d las fintech"}]},{"@type":"WebSite","@id":"https:\/\/gysfm.com.ar\/inicio\/#website","url":"https:\/\/gysfm.com.ar\/inicio\/","name":"GYS NOTICIAS |","description":"DIARIO - RADIO ONLINE SAN JUAN ARGENTINA","publisher":{"@id":"https:\/\/gysfm.com.ar\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gysfm.com.ar\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gysfm.com.ar\/inicio\/#organization","name":"GYS NOTICIAS |","url":"https:\/\/gysfm.com.ar\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2023\/07\/LOGOGYS-OK.png","contentUrl":"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2023\/07\/LOGOGYS-OK.png","width":1170,"height":872,"caption":"GYS NOTICIAS |"},"image":{"@id":"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/person\/5bedd7ecd35cc35548d89effafa23696","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c331d312b5243fb64d5ba28108a447b27c925295129a363082c9ea52c28d32c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c331d312b5243fb64d5ba28108a447b27c925295129a363082c9ea52c28d32c2?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/gysfm.com.ar\/inicio"],"url":"https:\/\/gysfm.com.ar\/inicio\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/posts\/208855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/comments?post=208855"}],"version-history":[{"count":1,"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/posts\/208855\/revisions"}],"predecessor-version":[{"id":208857,"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/posts\/208855\/revisions\/208857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/media\/208856"}],"wp:attachment":[{"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/media?parent=208855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/categories?post=208855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/tags?post=208855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}