{"id":196255,"date":"2026-05-13T08:46:29","date_gmt":"2026-05-13T11:46:29","guid":{"rendered":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/"},"modified":"2026-05-13T08:46:30","modified_gmt":"2026-05-13T11:46:30","slug":"el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran","status":"publish","type":"post","link":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/","title":{"rendered":"El Pent\u00e1gono estim\u00f3 en 29.000 millones de d\u00f3lares el costo de la guerra en Ir\u00e1n"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"com-paragraph --capital --s text-left\">WASHINGTON.\u2013 <strong>El costo de la guerra con Ir\u00e1n se acerca a los 29.000 millones de d\u00f3lares, unos 4000 millones m\u00e1s que lo estimado hace dos semanas<\/strong>, indic\u00f3 este martes el Pent\u00e1gono, en momentos en que el presidente <strong>Donald Trump <\/strong>enfrenta un creciente escrutinio por el conflicto.<\/p>\n<p class=\"com-paragraph --s text-left\">La nueva cifra fue revelada por el Departamento de Defensa durante una audiencia en el Capitolio en la que el secretario de Defensa,<strong> Pete Hegseth<\/strong>, y el general<strong> Dan Caine<\/strong>, jefe del Estado Mayor Conjunto, testificaban sobre una solicitud presupuestaria hist\u00f3rica de <strong>1,5 billones de d\u00f3lares para 2027.<\/strong><\/p>\n<p class=\"com-paragraph --s text-left\">En esa audiencia, en la que tambi\u00e9n particip\u00f3 <strong>Jules Hurst III<\/strong>, director financiero del Pent\u00e1gono, los legisladores pidieron una actualizaci\u00f3n del costo de la guerra.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" tabindex=\"0\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">El secretario de Guerra de Estados Unidos, Pete Hegseth, llega para testificar ante el Comit\u00e9 de Asignaciones del Senado sobre la solicitud de presupuesto para el a\u00f1o fiscal 2027 en el Edificio de Oficinas del Senado Dirksen en el Capitolio.<\/span><span class=\"com-text --credit --twoxs\">CHIP SOMODEVILLA &#8211; GETTY IMAGES NORTH AMERICA<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph --s text-left\">\u201cAl momento del testimonio (&#8230;) eran 25.000 millones de d\u00f3lares\u201d, dijo Hurst a los congresistas en referencia al estimado entregado por Hegseth el 29 de abril.<\/p>\n<p class=\"com-paragraph --s text-left\">Pero una revisi\u00f3n acerc\u00f3 la cifra al estimado actual, indic\u00f3 el jefe del Estado Mayor Conjunto, y cit\u00f3 actualizaciones en <strong>\u201ccostos de reparaci\u00f3n y sustituci\u00f3n de equipo\u201d<\/strong> y mayores gastos operativos.<\/p>\n<p class=\"com-paragraph --s text-left\">Presionado sobre cu\u00e1ndo el Congreso recibir\u00e1 un reporte completo de los costos de la guerra, Hegseth declar\u00f3 que la administraci\u00f3n requerir\u00e1 \u201clo que sea que pensemos que es necesario\u201d.<\/p>\n<p class=\"com-paragraph --s text-left\">Fue la primera audiencia de Hegseth en el Capitolio desde que la Casa Blanca notific\u00f3 formalmente al Congreso que las hostilidades, iniciadas por Estados Unidos e Israel el pasado 28 de febrero, hab\u00edan \u201cterminado\u201d.<\/p>\n<p class=\"com-paragraph --s text-left\">El senador dem\u00f3crata<strong> Mark Kelly <\/strong>advirti\u00f3 el fin de semana que las existencias de misiles Tomahawk, interceptores Patriot y otros sistemas avanzados se hab\u00edan reducido gravemente.<\/p>\n<p class=\"com-paragraph --s text-left\">Pero Hegseth desestim\u00f3 esas advertencias.<strong> \u201cEl problema de las municiones se ha exagerado de manera necia e in\u00fatil\u201d, dijo. \u201cSabemos exactamente lo que tenemos\u201d.<\/strong><\/p>\n<p class=\"com-paragraph --s text-left\">El testimonio se produjo cuando el alto el fuego entre Estados Unidos e Ir\u00e1n parece cada vez m\u00e1s fr\u00e1gil. Trump advirti\u00f3 el lunes que la tregua estaba en estado cr\u00edtico.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" tabindex=\"0\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">El secretario de Defensa de Estados Unidos, Pete Hegseth, testifica durante una audiencia del Subcomit\u00e9 de Defensa del Comit\u00e9 de Asignaciones del Senado para examinar el presupuesto de 2027 del Departamento de Defensa en el Capitolio en Washington, D.C., el 12 de mayo de 2026.<\/span><span class=\"com-text --credit --twoxs\">JIM WATSON &#8211; AFP<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph --s\">Los influyentes subcomit\u00e9s de asignaciones presupuestarias de la C\u00e1mara de Representantes y del Senado que supervisan el gasto en defensa est\u00e1n celebrando audiencias consecutivas <strong>para revisar la propuesta de presupuesto militar del gobierno para 2027. <\/strong><\/p>\n<p class=\"com-paragraph --s\">Pero las discusiones en la C\u00e1mara se desviaron r\u00e1pidamente hacia la gesti\u00f3n de una guerra que parece estancada, mientras el aumento de los precios del combustible plantea problemas pol\u00edticos para los republicanos en las elecciones legislativas de mitad de mandato.<\/p>\n<p class=\"com-paragraph --s\">La representante Rosa DeLauro, la principal dem\u00f3crata en el Comit\u00e9 de Asignaciones Presupuestarias de la C\u00e1mara, le dijo a Hegseth que <strong>\u201cla pregunta que debe responderse al final de esta crisis es \u00bfqu\u00e9 hemos logrado y a qu\u00e9 costo?\u201d<\/strong><\/p>\n<p class=\"com-paragraph --s\">\u201cEste gobierno<strong> no ha presentado al Congreso ning\u00fan tipo de estrategia clara o coherente <\/strong>semana a semana, d\u00eda a d\u00eda, hora a hora\u201d, sostuvo DeLauro. \u201cLa justificaci\u00f3n cambia, los objetivos cambian. El objetivo final est\u00e1 mal definido cuando es que se define\u201d.<\/p>\n<p class=\"com-paragraph --s\">Por su parte el representante republicano por California <strong>Ken Calvert<\/strong>, presidente del subcomit\u00e9 de la C\u00e1mara, tambi\u00e9n pregunt\u00f3 por el impacto de la guerra en el financiamiento militar, as\u00ed como en las reservas de armas de las fuerzas armadas.<\/p>\n<p class=\"com-paragraph --s\">\u201cPersisten las dudas sobre si estamos construyendo la profundidad y la resiliencia necesarias para un conflicto de alta intensidad\u201d, afirm\u00f3 Calvert.<\/p>\n<p class=\"com-paragraph --s\">La representante por Minnesota <strong>Betty McCollum<\/strong>, la principal dem\u00f3crata del subcomit\u00e9 de defensa, presion\u00f3 a Hegseth sobre<strong> si el ej\u00e9rcito tiene un plan para reducir tropas en Medio Oriente<\/strong> si el Congreso aprueba los esfuerzos para poner fin a la guerra con Ir\u00e1n.<\/p>\n<p class=\"com-paragraph --s\">\u201cTenemos un plan para escalar si es necesario\u201d, respondi\u00f3 Hegseth. \u201cTenemos un plan para replegarnos si es necesario. Tenemos un plan para redistribuir activos\u201d. Pero aclar\u00f3 que no revelar\u00eda p\u00fablicamente los pr\u00f3ximos pasos. <\/p>\n<p class=\"com-paragraph --s\">Al se\u00f1alar las reiteradas preguntas de los legisladores sobre la merma de las reservas de armas, Hegseth indic\u00f3 que la industria de defensa ha recibido \u00f3rdenes de<strong> \u201cfabricar m\u00e1s y r\u00e1pido\u201d<\/strong> y atribuy\u00f3 la capacidad insuficiente a gobiernos anteriores y a la ayuda a Ucrania en su guerra con Rusia.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" tabindex=\"0\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">Petroleros anclados en el estrecho de Ormuz, frente a Bandar Abbas, Ir\u00e1n<\/span><span class=\"com-text --credit --twoxs\">Amirhosein Khorgooi &#8211; ISNA<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph --s\">El presidente Donald Trump enfrenta una presi\u00f3n creciente por los impactos econ\u00f3micos de que <strong>Ir\u00e1n haya cerrado de facto el estrecho de Ormuz, un corredor mar\u00edtimo vital por el que normalmente circula el 20% del petr\u00f3leo mundial. <\/strong>A su vez, las fuerzas estadounidenses han bloqueado puertos iran\u00edes y ambas partes han intercambiado ataques, mientras fuerzas estadounidenses frustraban agresiones contra sus buques de guerra e inutilizaban petroleros vinculados a Teher\u00e1n.<\/p>\n<p class=\"com-paragraph --s\">Trump declar\u00f3 el lunes que<a href=\"https:\/\/www.lanacion.com.ar\/estados-unidos\/la-frustracion-de-trump-sin-las-cartas-a-su-favor-en-iran-nid11052026\/\" target=\"_self\" title=\"https:\/\/www.lanacion.com.ar\/estados-unidos\/la-frustracion-de-trump-sin-las-cartas-a-su-favor-en-iran-nid11052026\/\" class=\"com-link break-word\" data-mrf-recirculation=\"n_link_parrafo\"> el alto el fuego est\u00e1 en \u201csoporte vital\u201d <\/a>y critic\u00f3 a Ir\u00e1n por su propuesta m\u00e1s reciente, insistiendo en que Teher\u00e1n debe limitar su programa nuclear.<\/p>\n<p class=\"com-paragraph --s\">\u201cDir\u00eda que (la tregua) ahora mismo es lo m\u00e1s d\u00e9bil que ha estado, <strong>despu\u00e9s de leer ese pedazo de basura que nos enviaron<\/strong>\u201d, declar\u00f3 Trump.<\/p>\n<p class=\"com-paragraph --s\">El presidente republicano tambi\u00e9n dijo que quer\u00eda suspender el impuesto federal a la gasolina para ayudar a los estadounidenses a afrontar el alza de los precios del combustible. <strong>Anteriormente hab\u00eda dicho que val\u00eda la pena pagar m\u00e1s con tal de impedirle a Ir\u00e1n tener un arma nuclear.<\/strong><\/p>\n<p class=\"com-paragraph --s\">La audiencia del Senado m\u00e1s tarde el martes incluir\u00e1 a la senadora <strong>Susan Collins<\/strong>, de Maine, una republicana cuya reelecci\u00f3n este a\u00f1o est\u00e1 lejos de estar garantizada. Ella vot\u00f3 con los dem\u00f3cratas en un intento por detener el conflicto a finales del mes pasado, al afirmar que quiere ver una estrategia definida para llevar la guerra a su fin.<\/p>\n<p class=\"com-paragraph --s\">La senadora<strong> Lisa Murkowski<\/strong>, de Alaska, otra republicana en el subcomit\u00e9 de defensa de asignaciones presupuestarias del Senado, ha votado en contra de las resoluciones sobre poderes de guerra, pero ha hablado de la necesidad de una autorizaci\u00f3n del Congreso para que los estadounidenses conozcan los l\u00edmites y objetivos de la guerra.<\/p>\n<p class=\"com-paragraph --s\">Tambi\u00e9n enfrentar\u00e1 a muchos republicanos afines, incluido el presidente del subcomit\u00e9 del Senado, el senador Mitch McConnell de Kentucky, y quiz\u00e1 el mayor impulsor de la guerra con Ir\u00e1n en el Congreso, el senador Lindsey Graham de Carolina del Sur.<\/p>\n<p class=\"com-paragraph --s\"><strong>Agencias AP y AFP<\/strong><\/p>\n<section class=\"container-center-100 mb-40 border border-bottom border-thin border-neutral-light-700\">\n<hr\/>\n<\/section>\n<\/div>\n<p><script id=\"facebookpixel\" defer=\"\" type=\"text\/javascript\">\n        !function(f,b,e,v,n,t,s)\n        {if(f.fbq)return;n=f.fbq=function(){n.callMethod?\n        n.callMethod.apply(n,arguments):n.queue.push(arguments)};\n        if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';\n        n.queue=[];t=b.createElement(e);t.async=!0;\n        t.src=v;s=b.getElementsByTagName(e)[0];\n        s.parentNode.insertBefore(t,s)}(window, document,'script',\n        'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n        fbq('init', '492459597522335');\n        fbq('track', 'PageView');\n    <\/script><br \/>\n<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON.\u2013 El costo de la guerra con Ir\u00e1n se acerca a los 29.000 millones de d\u00f3lares, unos 4000 millones m\u00e1s que lo estimado hace dos semanas, indic\u00f3 este martes el Pent\u00e1gono, en momentos en que el presidente Donald Trump enfrenta un creciente escrutinio por el conflicto. La nueva cifra fue revelada por el Departamento de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":196256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-196255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Pent\u00e1gono estim\u00f3 en 29.000 millones de d\u00f3lares el costo de la guerra en Ir\u00e1n - GYS NOTICIAS |<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Pent\u00e1gono estim\u00f3 en 29.000 millones de d\u00f3lares el costo de la guerra en Ir\u00e1n - GYS NOTICIAS |\" \/>\n<meta property=\"og:description\" content=\"WASHINGTON.\u2013 El costo de la guerra con Ir\u00e1n se acerca a los 29.000 millones de d\u00f3lares, unos 4000 millones m\u00e1s que lo estimado hace dos semanas, indic\u00f3 este martes el Pent\u00e1gono, en momentos en que el presidente Donald Trump enfrenta un creciente escrutinio por el conflicto. La nueva cifra fue revelada por el Departamento de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/\" \/>\n<meta property=\"og:site_name\" content=\"GYS NOTICIAS |\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T11:46:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T11:46:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/05\/de-izquierda-a-derecha-el-subsecretario-de-3TCZN763HNADVBCRWLRNXNLLTQ.JPG\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Prensa G&amp;S FM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prensa G&amp;S FM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/\"},\"author\":{\"name\":\"Prensa G&amp;S FM\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/person\/3abba7593ef2ad19e1be221d54383dc5\"},\"headline\":\"El Pent\u00e1gono estim\u00f3 en 29.000 millones de d\u00f3lares el costo de la guerra en Ir\u00e1n\",\"datePublished\":\"2026-05-13T11:46:29+00:00\",\"dateModified\":\"2026-05-13T11:46:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/\"},\"wordCount\":1183,\"publisher\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#organization\"},\"image\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/05\/de-izquierda-a-derecha-el-subsecretario-de-3TCZN763HNADVBCRWLRNXNLLTQ.JPG\",\"articleSection\":[\"INTERNACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/\",\"url\":\"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/\",\"name\":\"El Pent\u00e1gono estim\u00f3 en 29.000 millones de d\u00f3lares el costo de la guerra en Ir\u00e1n - GYS NOTICIAS |\",\"isPartOf\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/05\/de-izquierda-a-derecha-el-subsecretario-de-3TCZN763HNADVBCRWLRNXNLLTQ.JPG\",\"datePublished\":\"2026-05-13T11:46:29+00:00\",\"dateModified\":\"2026-05-13T11:46:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/#primaryimage\",\"url\":\"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/05\/de-izquierda-a-derecha-el-subsecretario-de-3TCZN763HNADVBCRWLRNXNLLTQ.JPG\",\"contentUrl\":\"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/05\/de-izquierda-a-derecha-el-subsecretario-de-3TCZN763HNADVBCRWLRNXNLLTQ.JPG\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/gysfm.com.ar\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Pent\u00e1gono estim\u00f3 en 29.000 millones de d\u00f3lares el costo de la guerra en Ir\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#website\",\"url\":\"https:\/\/gysfm.com.ar\/inicio\/\",\"name\":\"GYS NOTICIAS |\",\"description\":\"DIARIO - RADIO ONLINE SAN JUAN ARGENTINA\",\"publisher\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gysfm.com.ar\/inicio\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#organization\",\"name\":\"GYS NOTICIAS |\",\"url\":\"https:\/\/gysfm.com.ar\/inicio\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2023\/07\/LOGOGYS-OK.png\",\"contentUrl\":\"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2023\/07\/LOGOGYS-OK.png\",\"width\":1170,\"height\":872,\"caption\":\"GYS NOTICIAS |\"},\"image\":{\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/person\/3abba7593ef2ad19e1be221d54383dc5\",\"name\":\"Prensa G&amp;S FM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/096ec78df02049ab018702bb4ccedf659377fa92a26540b5247612077a0dbd29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/096ec78df02049ab018702bb4ccedf659377fa92a26540b5247612077a0dbd29?s=96&d=mm&r=g\",\"caption\":\"Prensa G&amp;S FM\"},\"sameAs\":[\"https:\/\/gysfm.com.ar\/\"],\"url\":\"https:\/\/gysfm.com.ar\/inicio\/author\/lucasm\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Pent\u00e1gono estim\u00f3 en 29.000 millones de d\u00f3lares el costo de la guerra en Ir\u00e1n - GYS NOTICIAS |","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/","og_locale":"es_ES","og_type":"article","og_title":"El Pent\u00e1gono estim\u00f3 en 29.000 millones de d\u00f3lares el costo de la guerra en Ir\u00e1n - GYS NOTICIAS |","og_description":"WASHINGTON.\u2013 El costo de la guerra con Ir\u00e1n se acerca a los 29.000 millones de d\u00f3lares, unos 4000 millones m\u00e1s que lo estimado hace dos semanas, indic\u00f3 este martes el Pent\u00e1gono, en momentos en que el presidente Donald Trump enfrenta un creciente escrutinio por el conflicto. La nueva cifra fue revelada por el Departamento de [&hellip;]","og_url":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/","og_site_name":"GYS NOTICIAS |","article_published_time":"2026-05-13T11:46:29+00:00","article_modified_time":"2026-05-13T11:46:30+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/05\/de-izquierda-a-derecha-el-subsecretario-de-3TCZN763HNADVBCRWLRNXNLLTQ.JPG","type":"image\/jpeg"}],"author":"Prensa G&amp;S FM","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Prensa G&amp;S FM","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/#article","isPartOf":{"@id":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/"},"author":{"name":"Prensa G&amp;S FM","@id":"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/person\/3abba7593ef2ad19e1be221d54383dc5"},"headline":"El Pent\u00e1gono estim\u00f3 en 29.000 millones de d\u00f3lares el costo de la guerra en Ir\u00e1n","datePublished":"2026-05-13T11:46:29+00:00","dateModified":"2026-05-13T11:46:30+00:00","mainEntityOfPage":{"@id":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/"},"wordCount":1183,"publisher":{"@id":"https:\/\/gysfm.com.ar\/inicio\/#organization"},"image":{"@id":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/#primaryimage"},"thumbnailUrl":"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/05\/de-izquierda-a-derecha-el-subsecretario-de-3TCZN763HNADVBCRWLRNXNLLTQ.JPG","articleSection":["INTERNACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/","url":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/","name":"El Pent\u00e1gono estim\u00f3 en 29.000 millones de d\u00f3lares el costo de la guerra en Ir\u00e1n - GYS NOTICIAS |","isPartOf":{"@id":"https:\/\/gysfm.com.ar\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/#primaryimage"},"image":{"@id":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/#primaryimage"},"thumbnailUrl":"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/05\/de-izquierda-a-derecha-el-subsecretario-de-3TCZN763HNADVBCRWLRNXNLLTQ.JPG","datePublished":"2026-05-13T11:46:29+00:00","dateModified":"2026-05-13T11:46:30+00:00","breadcrumb":{"@id":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/#primaryimage","url":"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/05\/de-izquierda-a-derecha-el-subsecretario-de-3TCZN763HNADVBCRWLRNXNLLTQ.JPG","contentUrl":"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2026\/05\/de-izquierda-a-derecha-el-subsecretario-de-3TCZN763HNADVBCRWLRNXNLLTQ.JPG","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/gysfm.com.ar\/inicio\/el-pentagono-estimo-en-29-000-millones-de-dolares-el-costo-de-la-guerra-en-iran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gysfm.com.ar\/inicio\/"},{"@type":"ListItem","position":2,"name":"El Pent\u00e1gono estim\u00f3 en 29.000 millones de d\u00f3lares el costo de la guerra en Ir\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/gysfm.com.ar\/inicio\/#website","url":"https:\/\/gysfm.com.ar\/inicio\/","name":"GYS NOTICIAS |","description":"DIARIO - RADIO ONLINE SAN JUAN ARGENTINA","publisher":{"@id":"https:\/\/gysfm.com.ar\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gysfm.com.ar\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gysfm.com.ar\/inicio\/#organization","name":"GYS NOTICIAS |","url":"https:\/\/gysfm.com.ar\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2023\/07\/LOGOGYS-OK.png","contentUrl":"https:\/\/gysfm.com.ar\/inicio\/wp-content\/uploads\/2023\/07\/LOGOGYS-OK.png","width":1170,"height":872,"caption":"GYS NOTICIAS |"},"image":{"@id":"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/person\/3abba7593ef2ad19e1be221d54383dc5","name":"Prensa G&amp;S FM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gysfm.com.ar\/inicio\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/096ec78df02049ab018702bb4ccedf659377fa92a26540b5247612077a0dbd29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/096ec78df02049ab018702bb4ccedf659377fa92a26540b5247612077a0dbd29?s=96&d=mm&r=g","caption":"Prensa G&amp;S FM"},"sameAs":["https:\/\/gysfm.com.ar\/"],"url":"https:\/\/gysfm.com.ar\/inicio\/author\/lucasm\/"}]}},"_links":{"self":[{"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/posts\/196255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/comments?post=196255"}],"version-history":[{"count":1,"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/posts\/196255\/revisions"}],"predecessor-version":[{"id":196257,"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/posts\/196255\/revisions\/196257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/media\/196256"}],"wp:attachment":[{"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/media?parent=196255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/categories?post=196255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gysfm.com.ar\/inicio\/wp-json\/wp\/v2\/tags?post=196255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}